{"id":12244,"date":"2019-07-05T23:09:11","date_gmt":"2019-07-05T23:09:11","guid":{"rendered":"https:\/\/cosmicattitude.com\/?page_id=12244"},"modified":"2019-08-07T19:08:05","modified_gmt":"2019-08-07T19:08:05","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/cosmicattitude.com\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de Confidentialit\u00e9"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">INFORMATIONS SUR NOTRE ORGANISATION ET SITES WEB<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cette politique de confidentialit\u00e9&nbsp;nous vous&nbsp;informons&nbsp;sur les pratiques de confidentialit\u00e9, les choix&nbsp;que vous avez concernant&nbsp;la&nbsp;fa\u00e7on dont nous collectons&nbsp;vos informations&nbsp;en&nbsp;ligne, la fa\u00e7on dont nous utilisons&nbsp;ces informations et vos droits en utilisant ce site Web r\u00e9gi par les r\u00e8gles g\u00e9n\u00e9rales de protection des donn\u00e9es 2016\/679 (\u00ab&nbsp;GDPR&nbsp;\u00bb).&nbsp;S\u2019il vous pla\u00eet lisez attentivement cette Politique de confidentialit\u00e9 et&nbsp;s\u2019il vous pla\u00eet&nbsp;visitez r\u00e9guli\u00e8rement cette page pour voir les modifications qui ont \u00e9t\u00e9 apport\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous pouvons modifier cette Politique de confidentialit\u00e9 \u00e0 tout moment et publier les conditions modifi\u00e9es sur ce site.&nbsp;Tous les termes modifi\u00e9s&nbsp;seront valides au moment de la mise \u00e0 jour de la&nbsp;Politique de confidentialit\u00e9 publi\u00e9e, sauf indication contraire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SITES QUE CETTE POLITIQUE DE CONFIDENTIALIT\u00c9 COUVRE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cette Politique de confidentialit\u00e9 s\u2019applique&nbsp;au site Web www.cosmicattitude.com.&nbsp;Ce&nbsp;site Web&nbsp;peut fournir des liens vers des sites Web tiers pour votre commodit\u00e9 et votre information. Si vous acc\u00e9dez \u00e0 ces liens, vous quitterez&nbsp;le&nbsp;site.&nbsp;Nous n\u2019avons aucun contr\u00f4le sur les sites&nbsp;et les redirections&nbsp;ni sur leurs pratiques de confidentialit\u00e9, qui peuvent diff\u00e9rer de nos pratiques de confidentialit\u00e9.&nbsp;Cette Politique de confidentialit\u00e9 ne couvre pas les donn\u00e9es personnelles que vous choisissez de fournir \u00e0 des tiers ind\u00e9pendants.&nbsp;Nous ne surveillons ni ne contr\u00f4lons les informations collect\u00e9es par ces sites ni les pratiques de tiers en mati\u00e8re de confidentialit\u00e9, et nous ne sommes pas responsables de leurs pratiques ou du contenu de leurs sites.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">TYPES D\u2019INFORMATIONS QUE NOUS COLLECTONS ET UTILISONS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cette&nbsp;politique de \u00abdonn\u00e9es personnelles\u00bb d\u00e9signe des informations sur une personne identifiable qui est susceptible d\u2019\u00eatre prot\u00e9g\u00e9e par la loi en vigueur dans la juridiction dans laquelle elle r\u00e9side.&nbsp;Dans certaines juridictions, les \u00ab&nbsp;informations personnelles&nbsp;\u00bb ou les \u00ab&nbsp;donn\u00e9es personnelles&nbsp;\u00bb n\u2019incluent pas les informations de contact professionnel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le site web on recueille des\u00a0informations \u00e0\u00a0travers une vari\u00e9t\u00e9 de fa\u00e7ons et \u00e0\u00a0des\u00a0fins diff\u00e9rentes,\u00a0comme indiqu\u00e9 ci-dessous.\u00a0Si vous choisissez de vous inscrire sur\u00a0le\u00a0site Web pour recevoir nos mises \u00e0 jour, g\u00e9rer votre compte et\/ou utiliser notre portail en libre-service, vous serez invit\u00e9 \u00e0 fournir vos informations de contact (nom, adresse, num\u00e9ro de t\u00e9l\u00e9phone, adresse e-mail, nom utilisateur unique et mot de passe).\u00a0Nous utilisons ces informations conform\u00e9ment \u00e0 nos int\u00e9r\u00eats commerciaux l\u00e9gitimes pour fournir nos services et ou pour vous contacter \u00e0 propos des services propos\u00e9s sur notre site o\u00f9 vous avez exprim\u00e9 un int\u00e9r\u00eat. Les donn\u00e9es sont collect\u00e9es gr\u00e2ce \u00e0 votre consentement libre, exprim\u00e9 et justifi\u00e9 dans un acte de validation et la facilit\u00e9 avec laquelle vous les rendez disponibles est la m\u00eame que celle applicable \u00e0 l&rsquo;annulation. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous pouvons \u00e9galement utiliser vos informations de contact pour vous envoyer des informations sur les produits et services de tiers, telles que les salles de r\u00e9union,&nbsp;les&nbsp;bureaux&nbsp;virtuels, les bureaux, le coworking et les adh\u00e9sions, tant que nous avons obtenu votre consentement conform\u00e9ment \u00e0 la loi applicable.&nbsp;Si vous ne souhaitez pas recevoir ces annonces promotionnelles de mani\u00e8re continue, vous&nbsp;pouvez&nbsp;vous&nbsp;d\u00e9sinscrire \u00e0 tout moment dans la section inf\u00e9rieure de nos infolettres.&nbsp;&nbsp;&nbsp;Vous avez \u00e9galement la possibilit\u00e9 de fournir des informations d\u00e9mographiques (telles que le type d\u2019entreprise, la taille de l\u2019entreprise, les sites, etc.).&nbsp;Nous utilisons ces informations d\u00e9mographiques pour comprendre vos besoins et vos int\u00e9r\u00eats et pour vous offrir une exp\u00e9rience plus personnalis\u00e9e sur notre site.&nbsp;Les informations sont utilis\u00e9es par le groupe pour traiter vos commandes, permettre la participation \u00e0 des promotions (sous r\u00e9serve de vos pr\u00e9f\u00e9rences en mati\u00e8re de marketing) et nous permettre de vous fournir nos services.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le\u00a0site Web, vous pouvez demander des produits ou des services, demander des informations ou vous abonner \u00e0 des supports marketing ou\u00a0demander de l\u2019aide\u00a0dans notre chat\u00a0.\u00a0Afin d\u2019acheter un de nos produits ou services, nous vous demanderons certaines informations vous concernant qui seront utilis\u00e9es \u00e0 des fins de conformit\u00e9 du contrat.\u00a0Vous devez fournir les informations de contact (telles que le nom, l\u2019adresse \u00e9lectronique et l\u2019adresse de livraison) et les informations financi\u00e8res (telles que le num\u00e9ro de carte de cr\u00e9dit, l\u2019adresse de facturation et la date d\u2019expiration).\u00a0Les informations financi\u00e8res collect\u00e9es \u00e0 votre sujet sont utilis\u00e9es uniquement pour vous facturer les produits et services que vous avez achet\u00e9s\u00a0chez nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le but de la collecte et le traitement des donn\u00e9es personnelles sont la r\u00e9alisation de campagnes de marketing direct. Les donn\u00e9es seront uniquement trait\u00e9es \u00e0 cet effet d\u00e9termin\u00e9, explicit et l\u00e9gitime, ne pourront pas \u00eatre trait\u00e9es ult\u00e9rieurement de mani\u00e8re incompatible. Les donn\u00e9es collect\u00e9es et trait\u00e9es sont ad\u00e9quates, pertinentes et non excessives au regard de cet effet. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cas de collecter des informations de votre carte de cr\u00e9dit, nous les utilisons uniquement pour le traitement des paiements et la pr\u00e9vention de la fraude.&nbsp;Cosmicattitude&nbsp;n\u2019utilise pas les informations de votre carte de cr\u00e9dit, ni d\u2019autres informations personnelles tout aussi sensibles, \u00e0 d\u2019autres fins.&nbsp;Apr\u00e8s avoir trait\u00e9 un paiement, nous ne&nbsp;conservons&nbsp;pas&nbsp;les informations de votre carte de cr\u00e9dit, \u00e0 moins que vous ne nous donniez la permission de les conserver pour vos futurs achats&nbsp;ou les paiements r\u00e9currents.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le site Web collecte&nbsp;automatiquement des informations techniques sur votre visite (tel que le type de navigateur, fournisseur de service Internet, type de plate-forme, adresses IP,&nbsp;sites de&nbsp;r\u00e9f\u00e9rence et de sortie, syst\u00e8me d\u2019exploitation, et l\u2019horodatage).&nbsp;Nous agroupons ces informations&nbsp;pour g\u00e9n\u00e9rer des rapports sur le site Web&nbsp;afin d\u2019analyser les tendances, de diagnostiquer les probl\u00e8mes li\u00e9s \u00e0&nbsp;la gestion de nos serveurs et de nos donn\u00e9es, de suivre les mouvements et l\u2019utilisation des utilisateurs et de collecter des informations d\u00e9mographiques g\u00e9n\u00e9rales.&nbsp;Pour plus d\u2019informations, voir \u00abCookies et autres signets num\u00e9riques\u00bb ci-dessous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est possible que nous soyons amen\u00e9s \u00e0 partager des informations avec des tiers en vertu de la loi applicable.&nbsp;Par exemple, il peut nous \u00eatre demand\u00e9 de divulguer des informations \u00e0 la suite d\u2019une ordonnance judiciaire, d\u2019une assignation \u00e0 compara\u00eetre ou d\u2019une ordonnance du tribunal.&nbsp;En outre, nous pouvons, sur la base du droit applicable, fournir des informations sur une base volontaire afin de faciliter une enqu\u00eate sur le respect de la loi ou lorsque la divulgation est n\u00e9cessaire pour prot\u00e9ger nos syst\u00e8mes, nos activit\u00e9s ou les droits d\u2019autrui.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>MARKETING DIRECT ET COMMUNICATION DES DONN\u00c9ES \u00c0 DES TIERS<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois que vous vous \u00eates inscrit, nous vous enverrons un email de bienvenue pour v\u00e9rifier votre nom d\u2019utilisateur et votre mot de passe.&nbsp;Nous r\u00e9pondrons \u00e9galement \u00e0 vos questions, nous vous fournirons les services que vous demandez et nous g\u00e9rerons votre compte.&nbsp;Nous vous contacterons par e-mail ou par t\u00e9l\u00e9phone et nous mettrons tout en \u0153uvre pour satisfaire vos pr\u00e9f\u00e9rences.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous enverrons \u00e9galement des informations sur les nouveaux produits, services, \u00e9conomies sp\u00e9ciales, promotions et informations g\u00e9n\u00e9rales en fonction des pr\u00e9f\u00e9rences marketing que vous nous indiquez.&nbsp;Si vous ne souhaitez pas recevoir ces informations, vous pouvez vous d\u00e9sabonner&nbsp;pour ne plus recevoir de courrier (voir la section D\u00e9sabonnement ci-dessous).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous demandez \u00e0 vous abonner \u00e0 nos infolettres, nous utiliserons votre nom et votre adresse email pour vous envoyer l\u2019infolettre.&nbsp;Vous pouvez vous abonner \u00e0 nos lettres&nbsp;d\u2019information&nbsp;sur notre site Web.&nbsp;Vous pouvez annuler votre abonnement \u00e0&nbsp;tout moment (voir la&nbsp;section D\u00e9sabonnement ci-dessous).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si n\u00e9cessaire, nous vous ferons parvenir des publicit\u00e9s li\u00e9es au service qui ne sont pas de nature promotionnelle.&nbsp;Si&nbsp;vous&nbsp;ne souhaitez pas&nbsp;les&nbsp;recevoir,&nbsp;Vous pouvez&nbsp;vous&nbsp;d\u00e9sabonner \u00e0&nbsp;tout moment (voir la&nbsp;section ci-dessous&nbsp;Se&nbsp;d\u00e9sabonner).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pla\u00e7ant cliquant sur le bouton \u00abJ&rsquo;accepte\u00bb (ou \u00e9quivalent) sur les formulaires ou les chatbots, vous consentez \u00e0 recevoir des communications \u00e9lectroniques de marketing direct. Ces communications \u00e9lectroniques peuvent \u00eatre effectu\u00e9es par email, t\u00e9l\u00e9phone, t\u00e9l\u00e9phone mobile et SMS\/MMS, \u00e0 tout moment l&rsquo;utilisateur peut choisir le canal par lequel il souhaite \u00eatre contact\u00e9. Les communications seront effectu\u00e9es par cosmicattitude ou par ses partenaires, acceptant \u00e9galement qu&rsquo;Adclick puisse transmettre ses donn\u00e9es \u00e0 ses partenaires \u00e0 cette finalit\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les\u00a0<strong>\u00abpartenaires\u00bb<\/strong>de cosmicattitude sont des entit\u00e9s collectives, publiques ou priv\u00e9es, \u00e0 but lucratif ou non et qui sont habituellement identifi\u00e9s au moment de l\u2019inscription, ou non, mais qui appartiennent \u00e0 des cat\u00e9gories de l&rsquo;\u00e9sot\u00e9risme et de la spiritualit\u00e9. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9CHANGE D\u2019INFORMATIONS&nbsp;ET TRANSFERTS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons des contrats avec des prestataires de services et des fournisseurs externes pour des services et des solutions compl\u00e8tes aux clients d\u00e9crits ci-dessus.&nbsp;Ces fournisseurs de services peuvent changer ou nous pouvons faire appel \u00e0 des fournisseurs de services suppl\u00e9mentaires pour fournir un meilleur service \u00e0 nos clients.&nbsp;Nos affili\u00e9s peuvent vous fournir des services, \u00e0 vous ou \u00e0 votre affili\u00e9 local, et recevoir des informations personnelles \u00e0 votre sujet.&nbsp;Si nous transmettons vos donn\u00e9es personnelles \u00e0 des soci\u00e9t\u00e9s affili\u00e9es ou \u00e0 des tiers, nous demandons aux destinataires de vos donn\u00e9es personnelles de prot\u00e9ger vos donn\u00e9es personnelles par le biais de proc\u00e9dures administratives, techniques et de s\u00e9curit\u00e9;&nbsp;Toutefois, vos donn\u00e9es personnelles seront \u00e9galement soumises aux lois de la juridiction qui r\u00e9git notre soci\u00e9t\u00e9 affili\u00e9e ou un tiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vos donn\u00e9es personnelles peuvent \u00eatre transf\u00e9r\u00e9es et traverser les fronti\u00e8res \u00e9tatiques et nationales avec nos soci\u00e9t\u00e9s affili\u00e9es afin de fournir nos services.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vos donn\u00e9es sont conserv\u00e9es par cosmicattitude aux fins d\u00e9crites ci-dessus, et pour prouver votre inscription sur ce site, ainsi que pour prouver l&rsquo;exercice de vos droits, dans les d\u00e9lais autoris\u00e9s selon les lignes directrices des entit\u00e9s de surveillance. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">COOKIES ET AUTRES MARQUEURS NUM\u00c9RIQUES<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous recueillons automatiquement des informations via l\u2019utilisation de cookies et d\u2019autres signets num\u00e9riques.&nbsp;Les cookies et les signets num\u00e9riques sont de petits fichiers informatiques qui peuvent \u00eatre stock\u00e9s sur le disque dur de votre ordinateur ou int\u00e9gr\u00e9s aux pages de notre site Web, ce qui nous permet de vous identifier et de faire un suivi de votre visite sur celui-ci.&nbsp;Par exemple, lorsque vous r\u00e9servez un espace de bureau, nous utilisons des cookies dans le processus de paiement afin de garder une trace de votre commande \u00e0 chaque \u00e9tape du processus de r\u00e9servation.&nbsp;Nous pouvons utiliser des services tiers pour collecter et traiter des informations personnelles au moyen de l\u2019utilisation de cookies et autres signets num\u00e9riques en notre nom.&nbsp;Vous pouvez d\u00e9sactiver les cookies sur votre ordinateur en modifiant les param\u00e8tres dans les pr\u00e9f\u00e9rences ou dans le menu d\u2019options de votre navigateur.&nbsp;Si vous d\u00e9cidez de d\u00e9sactiver les cookies, vous ne pourrez peut-\u00eatre pas acc\u00e9der \u00e0 certaines zones du site Web.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">VOS OPTIONS ET EXCLUSION VOLONTAIRE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous offrons la possibilit\u00e9 de recevoir une vari\u00e9t\u00e9 d\u2019informations qui compl\u00e8te nos produits et services.&nbsp;Vous pouvez vous abonner pour recevoir des informations sp\u00e9cifiques sur les produits et les services, ainsi que des communications marketing pour l\u2019ensemble du groupe.&nbsp;Ces communications peuvent inclure des informations sur de nouveaux produits, des offres sp\u00e9ciales ou une invitation \u00e0 participer \u00e0 des \u00e9tudes de march\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous ne souhaitez plus recevoir nos lettres d\u2019information et\/ou communications promotionnelles, vous pouvez vous d\u00e9sabonner pour ne plus les recevoir en suivant les instructions fournies dans chaque&nbsp;lettre d\u2019information ou communication.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ACC\u00c8S ET EXACTITUDE DE VOS INFORMATIONS ET D\u2019AUTRES DROITS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dans certaines juridictions, notamment dans l\u2019Union europ\u00e9enne et au Royaume-Uni, vous avez le droit de nous: demander une copie de vos informations personnelles;&nbsp;nous demander de corriger, supprimer ou restreindre (arr\u00eater tout traitement actif) de vos donn\u00e9es personnelles et obtenir les donn\u00e9es personnelles que vous nous avez fournies pour un contrat ou avec votre consentement et nous demander de partager ces donn\u00e9es avec un autre contr\u00f4leur de donn\u00e9es (port);&nbsp;s\u2019opposer au traitement de vos informations personnelles de notre part dans certaines circonstances (en particulier, dans les cas o\u00f9 nous n\u2019avons pas \u00e0 traiter les donn\u00e9es pour se conformer \u00e0 une obligation contractuelle ou \u00e0 une autre obligation l\u00e9gale, ou dans les cas o\u00f9 nous utilisons les donn\u00e9es pour: marketing direct).&nbsp;Ces droits peuvent \u00eatre limit\u00e9s, par exemple si l\u2019ex\u00e9cution de votre demande r\u00e9v\u00e8le des donn\u00e9es personnelles sur une autre personne ou viole le droit \u00e0 la vie priv\u00e9e d\u2019autrui, ou si vous nous demandez de supprimer des informations que la loi nous oblige \u00e0 conserver ou que nous avons un int\u00e9r\u00eat l\u00e9gitime imp\u00e9rieux \u00e0 conserver.&nbsp;Pour exercer l\u2019un de ces&nbsp;droits, veuillez contacter&nbsp;contact@cosmicattitude.com&nbsp;Si vous avez des probl\u00e8mes non r\u00e9solus, vous avez le droit de d\u00e9poser une plainte aupr\u00e8s de l\u2019autorit\u00e9 de contr\u00f4le de la protection des donn\u00e9es o\u00f9 vous r\u00e9sidez, travaillez ou pensez qu\u2019une violation a pu se produire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">GARDER VOS INFORMATIONS EN SECURITE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous ne garantissons pas la s\u00e9curit\u00e9 de nos serveurs ni ne pouvons garantir que les informations que vous fournissez via le site Web ne seront pas intercept\u00e9es lors de leur transmission sur Internet.&nbsp;Nous suivons les normes techniques g\u00e9n\u00e9ralement accept\u00e9es du secteur pour prot\u00e9ger les donn\u00e9es personnelles que vous nous avez transmises, lors de leur transmission et une fois que nous les avons re\u00e7ues.&nbsp;Lorsque vous entrez des informations confidentielles (telles que des informations de carte de cr\u00e9dit) dans nos formulaires d\u2019inscription ou de commande, nous les cryptons \u00e0 l\u2019aide de la technologie de la couche de connexion s\u00e9curis\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque nous traitons des informations personnelles \u00e0 des fins de marketing ou avec votre consentement, nous les traitons jusqu\u2019\u00e0 ce que vous nous demandiez de cesser de le faire et pendant une courte p\u00e9riode apr\u00e8s cela (pour nous permettre de donner suite \u00e0 vos demandes).&nbsp;Nous conservons \u00e9galement un enregistrement de votre demande afin de ne pas vous envoyer de marketing direct ni traiter vos donn\u00e9es ind\u00e9finiment afin de respecter votre demande \u00e0 l\u2019avenir.&nbsp;Lorsque nous traitons des informations personnelles li\u00e9es \u00e0 l\u2019ex\u00e9cution d\u2019un contrat ou d\u2019un Service, ou \u00e0 un concours,&nbsp;nous conservons les informations (\u00e0 l\u2019exception des informations financi\u00e8res, que nous conservons pendant&nbsp;le temps que nos fournisseurs de services envisagent dans leurs politiques de confidentialit\u00e9) \u00e0 partir de la derni\u00e8re interaction avec nous.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">TRANSITIONS COMMERCIALES<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En cas o\u00f9 nous traversons une phase de transition d\u2019affaires, telle qu\u2019une fusion, une acquisition par une autre soci\u00e9t\u00e9 ou la vente de tout ou une partie de vos actifs, vos informations personnelles feront probablement partie des actifs transf\u00e9r\u00e9s<a href=\"http:\/\/joya.life\">.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/cosmicattitude.com\/termes-et-conditions\/?lang=fr\">TERMES ET CONDITIONS<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous choisissez de visiter notre site Web, votre visite et tout conflit li\u00e9 \u00e0 la confidentialit\u00e9 sont soumis \u00e0 la pr\u00e9sente Politique de confidentialit\u00e9 et \u00e0 nos conditions g\u00e9n\u00e9rales, y compris, sans limitation, l\u2019exon\u00e9ration de garantie, les limitations de responsabilit\u00e9 et la m\u00e9diation des litiges. Si vous avez des questions sur l\u2019utilisation que nous faisons de vos donn\u00e9es, envoyez un courrier \u00e9lectronique \u00e0 contact@cosmicattitude.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avril 201 9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INFORMATIONS SUR NOTRE ORGANISATION ET SITES WEB Dans cette politique de confidentialit\u00e9&nbsp;nous vous&nbsp;informons&nbsp;sur les pratiques de confidentialit\u00e9, les choix&nbsp;que vous avez concernant&nbsp;la&nbsp;fa\u00e7on dont nous collectons&nbsp;vos informations&nbsp;en&nbsp;ligne, la fa\u00e7on dont nous utilisons&nbsp;ces informations et vos droits en utilisant ce site Web r\u00e9gi par les r\u00e8gles g\u00e9n\u00e9rales de protection des donn\u00e9es 2016\/679 (\u00ab&nbsp;GDPR&nbsp;\u00bb).&nbsp;S\u2019il vous pla\u00eet lisez attentivement [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11438,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"class_list":["post-12244","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de Confidentialit\u00e9 - Cosmicattitute<\/title>\n<meta name=\"description\" content=\"Dans cette politique de confidentialit\u00e9 nous vous informons sur les pratiques de confidentialit\u00e9, les choix que vous avez concernant la fa\u00e7on dont nous...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmicattitude.com\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de Confidentialit\u00e9 - Cosmicattitute\" \/>\n<meta property=\"og:description\" content=\"Dans cette politique de confidentialit\u00e9 nous vous informons sur les pratiques de confidentialit\u00e9, les choix que vous avez concernant la fa\u00e7on dont nous...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmicattitude.com\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Cosmicattitute\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-07T19:08:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cosmicattitude.com\/wp-content\/uploads\/2019\/06\/image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"987\" \/>\n\t<meta property=\"og:image:height\" content=\"643\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/\",\"url\":\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/\",\"name\":\"Politique de Confidentialit\u00e9 - Cosmicattitute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cosmicattitude.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/image.png\",\"datePublished\":\"2019-07-05T23:09:11+00:00\",\"dateModified\":\"2019-08-07T19:08:05+00:00\",\"description\":\"Dans cette politique de confidentialit\u00e9 nous vous informons sur les pratiques de confidentialit\u00e9, les choix que vous avez concernant la fa\u00e7on dont nous...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cosmicattitude.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/image.png\",\"contentUrl\":\"https:\\\/\\\/cosmicattitude.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/image.png\",\"width\":987,\"height\":643,\"caption\":\"Pol\u00edtica de Privacidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/politica-de-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cosmicattitude.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de Confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/#website\",\"url\":\"https:\\\/\\\/cosmicattitude.com\\\/\",\"name\":\"Cosmicattitute\",\"description\":\"Powered!\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmicattitude.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/#organization\",\"name\":\"Cosmicattitude\",\"url\":\"https:\\\/\\\/cosmicattitude.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cosmicattitude.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cosmiclogo.png\",\"contentUrl\":\"https:\\\/\\\/cosmicattitude.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cosmiclogo.png\",\"width\":63,\"height\":63,\"caption\":\"Cosmicattitude\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmicattitude.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de Confidentialit\u00e9 - Cosmicattitute","description":"Dans cette politique de confidentialit\u00e9 nous vous informons sur les pratiques de confidentialit\u00e9, les choix que vous avez concernant la fa\u00e7on dont nous...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de Confidentialit\u00e9 - Cosmicattitute","og_description":"Dans cette politique de confidentialit\u00e9 nous vous informons sur les pratiques de confidentialit\u00e9, les choix que vous avez concernant la fa\u00e7on dont nous...","og_url":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/","og_site_name":"Cosmicattitute","article_modified_time":"2019-08-07T19:08:05+00:00","og_image":[{"width":987,"height":643,"url":"https:\/\/cosmicattitude.com\/wp-content\/uploads\/2019\/06\/image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/","url":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/","name":"Politique de Confidentialit\u00e9 - Cosmicattitute","isPartOf":{"@id":"https:\/\/cosmicattitude.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/#primaryimage"},"image":{"@id":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/cosmicattitude.com\/wp-content\/uploads\/2019\/06\/image.png","datePublished":"2019-07-05T23:09:11+00:00","dateModified":"2019-08-07T19:08:05+00:00","description":"Dans cette politique de confidentialit\u00e9 nous vous informons sur les pratiques de confidentialit\u00e9, les choix que vous avez concernant la fa\u00e7on dont nous...","breadcrumb":{"@id":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmicattitude.com\/politica-de-privacidad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/#primaryimage","url":"https:\/\/cosmicattitude.com\/wp-content\/uploads\/2019\/06\/image.png","contentUrl":"https:\/\/cosmicattitude.com\/wp-content\/uploads\/2019\/06\/image.png","width":987,"height":643,"caption":"Pol\u00edtica de Privacidad"},{"@type":"BreadcrumbList","@id":"https:\/\/cosmicattitude.com\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cosmicattitude.com\/home\/"},{"@type":"ListItem","position":2,"name":"Politique de Confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/cosmicattitude.com\/#website","url":"https:\/\/cosmicattitude.com\/","name":"Cosmicattitute","description":"Powered!","publisher":{"@id":"https:\/\/cosmicattitude.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmicattitude.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cosmicattitude.com\/#organization","name":"Cosmicattitude","url":"https:\/\/cosmicattitude.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cosmicattitude.com\/#\/schema\/logo\/image\/","url":"https:\/\/cosmicattitude.com\/wp-content\/uploads\/2019\/06\/cosmiclogo.png","contentUrl":"https:\/\/cosmicattitude.com\/wp-content\/uploads\/2019\/06\/cosmiclogo.png","width":63,"height":63,"caption":"Cosmicattitude"},"image":{"@id":"https:\/\/cosmicattitude.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/pages\/12244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/comments?post=12244"}],"version-history":[{"count":0,"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/pages\/12244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/media\/11438"}],"wp:attachment":[{"href":"https:\/\/cosmicattitude.com\/fr\/wp-json\/wp\/v2\/media?parent=12244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}